{"id":3097,"date":"2011-10-31T15:01:26","date_gmt":"2011-10-31T14:01:26","guid":{"rendered":"https:\/\/wctt.pwr.edu.pl\/?post_type=publication&#038;p=3097"},"modified":"2018-11-05T12:36:31","modified_gmt":"2018-11-05T11:36:31","slug":"2011_4","status":"publish","type":"publication","link":"https:\/\/wctt.pwr.edu.pl\/en\/publication\/2011_4\/","title":{"rendered":"2011_4"},"content":{"rendered":"","protected":false},"author":47,"featured_media":0,"template":"","class_list":["post-3097","publication","type-publication","status-publish","hentry","kategorie_publikacji-biuletyn-high-tech"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Magdalena Kasza","author_link":"https:\/\/wctt.pwr.edu.pl\/en\/author\/magkas\/"},"uagb_comment_info":0,"uagb_excerpt":null,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:01:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"kategorie_publikacji","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/3097","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/types\/publication"}],"author":[{"embeddable":true,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/users\/47"}],"version-history":[{"count":2,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/3097\/revisions"}],"predecessor-version":[{"id":3239,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/3097\/revisions\/3239"}],"wp:attachment":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/media?parent=3097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}