{"id":2998,"date":"2016-10-31T14:01:06","date_gmt":"2016-10-31T13:01:06","guid":{"rendered":"https:\/\/wctt.pwr.edu.pl\/?post_type=publication&#038;p=2998"},"modified":"2018-11-05T12:17:44","modified_gmt":"2018-11-05T11:17:44","slug":"2016_60","status":"publish","type":"publication","link":"https:\/\/wctt.pwr.edu.pl\/en\/publication\/2016_60\/","title":{"rendered":"2016_60"},"content":{"rendered":"","protected":false},"author":47,"featured_media":0,"template":"","class_list":["post-2998","publication","type-publication","status-publish","hentry","kategorie_publikacji-biuletyn-high-tech"],"acf":[],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false},"uagb_author_info":{"display_name":"Magdalena Kasza","author_link":"https:\/\/wctt.pwr.edu.pl\/en\/author\/magkas\/"},"uagb_comment_info":0,"uagb_excerpt":null,"publishpress_future_action":{"enabled":false,"date":"2026-05-20 02:31:27","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"kategorie_publikacji","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/2998","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/types\/publication"}],"author":[{"embeddable":true,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/users\/47"}],"version-history":[{"count":3,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/2998\/revisions"}],"predecessor-version":[{"id":3212,"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/publication\/2998\/revisions\/3212"}],"wp:attachment":[{"href":"https:\/\/wctt.pwr.edu.pl\/en\/wp-json\/wp\/v2\/media?parent=2998"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}